{"id":142,"date":"2024-03-18T20:32:48","date_gmt":"2024-03-18T20:32:48","guid":{"rendered":"https:\/\/www.se.senac.br\/pss\/?page_id=142"},"modified":"2024-03-18T20:32:48","modified_gmt":"2024-03-18T20:32:48","slug":"pss-03-2022","status":"publish","type":"page","link":"https:\/\/www.se.senac.br\/pss\/pss-03-2022\/","title":{"rendered":"PSS 03\/2022"},"content":{"rendered":"<p style=\"text-align: center;\"><strong>A inscri\u00e7\u00e3o ser\u00e1 feita em uma plataforma externa (e-inscri\u00e7\u00e3o).\u00a0 Ao clicar no bot\u00e3o abaixo,\u00a0<\/strong><br \/>\n<strong>n\u00e3o \u00e9 obrigat\u00f3ria a cria\u00e7\u00e3o de uma conta, basta efetuar o cadastro e aguardar o email de confirma\u00e7\u00e3o.<br \/>\nLembre-se, n\u00e3o h\u00e1 taxas ou valores a serem pagos.<br \/>\n<\/strong><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ff0000;\"><strong>INSCRI\u00c7\u00d5ES ENCERRADAS<\/strong><\/span><\/p>\n<p style=\"text-align: center;\"><div class='w3eden'>\n    <div class=''>\n\n        <form method=\"get\" class=\"__wpdm_submit_async\" data-container=\"#content_wpdm_package_1\" id=\"sc_form_wpdm_package_1\" style=\"margin-bottom: 15px\">\n    \n            <div class=\"card panel panel-default wpdm-shortcode-toolbar\">\n                <div class=\"card-body panel-body\">\n                    <div class=\"row\">\n                        <div class=\"col-lg-6 col-md-12\">\n                            <input type=\"search\" name=\"skw\" value=\"\" placeholder=\"Search Keyword...\" class=\"form-control\" \/>\n                        <\/div>\n                        <div class=\"col-lg-2 col-md-4\">\n                            <select name=\"orderby\" class=\"wpdm-custom-select custom-select\">\n                                <option value=\"date\" disabled=\"disabled\">Order By:<\/option>\n                                <option value=\"date\" > Data de Publica\u00e7\u00e3o<\/option>\n                                <option value=\"title\" >T\u00edtulo<\/option>\n                                <option value=\"update_date\" > Data de atualiza\u00e7\u00e3o<\/option>\n                                <option value=\"downloads\" >Downloads<\/option>\n                                <option value=\"views\" >Views<\/option>\n                            <\/select>\n                        <\/div>\n                        <div class=\"col-lg-2 col-md-4\">\n                            <select name=\"order\" class=\"wpdm-custom-select custom-select\">\n                                <option value=\"desc\" disabled=\"disabled\">Order:<\/option>\n                                <option value=\"desc\" >Descending<\/option>\n                                <option value=\"asc\" >Ascending<\/option>\n                            <\/select>\n                        <\/div>\n                        <div class=\"col-lg-2 col-md-4\">\n                            <button type=\"submit\" class=\"btn btn-info btn-block\">Apply Filter<\/button>\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n\n            <\/form>\n<div class=\"spacer mb-3 d-block clearfix\"><\/div>\n\n        <div id=\"content_wpdm_package_1\">\n            <div class='row'><div class='col-lg-12 col-md-6 col-12'><!-- WPDM Link Template: Default Template -->\n\n<div class=\"link-template-default card mb-2\">\n    <div class=\"card-body\">\n        <div class=\"media\">\n            <div class=\"mr-3 img-48\"><img decoding=\"async\" class=\"wpdm_icon\" alt=\"\u00edcone\" src=\"https:\/\/www.se.senac.br\/pss\/wp-content\/plugins\/download-manager\/assets\/file-type-icons\/pdf.svg\" \/><\/div>\n            <div class=\"media-body\">\n                <h3 class=\"package-title\"><a href='https:\/\/www.se.senac.br\/pss\/download\/setima-convocacao-pss-003-2022\/'>S\u00e9tima Convoca\u00e7\u00e3o PSS 003\/2022<\/a><\/h3>\n                <div class=\"text-muted text-small\"><i class=\"fas fa-copy\"><\/i> 1  arquivo(s) <i class=\"fas fa-hdd ml-3\"><\/i> 141.30 KB<\/div>\n            <\/div>\n            <div class=\"ml-3\">\n                <a class='wpdm-download-link download-on-click btn btn-primary ' rel='nofollow' href='#' data-downloadurl=\"https:\/\/www.se.senac.br\/pss\/download\/setima-convocacao-pss-003-2022\/?wpdmdl=160&refresh=6a04cf128c7091778700050\">Download<\/a>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<\/div><div class='col-lg-12 col-md-6 col-12'><!-- WPDM Link Template: Default Template -->\n\n<div class=\"link-template-default card mb-2\">\n    <div class=\"card-body\">\n        <div class=\"media\">\n            <div class=\"mr-3 img-48\"><img decoding=\"async\" class=\"wpdm_icon\" alt=\"\u00edcone\" src=\"https:\/\/www.se.senac.br\/pss\/wp-content\/plugins\/download-manager\/assets\/file-type-icons\/pdf.svg\" \/><\/div>\n            <div class=\"media-body\">\n                <h3 class=\"package-title\"><a href='https:\/\/www.se.senac.br\/pss\/download\/prorrogacao-do-processo-seletivo-003-2022\/'>Prorroga\u00e7\u00e3o do Processo Seletivo 003\/2022<\/a><\/h3>\n                <div class=\"text-muted text-small\"><i class=\"fas fa-copy\"><\/i> 1  arquivo(s) <i class=\"fas fa-hdd ml-3\"><\/i> 170.42 KB<\/div>\n            <\/div>\n            <div class=\"ml-3\">\n                <a class='wpdm-download-link download-on-click btn btn-primary ' rel='nofollow' href='#' data-downloadurl=\"https:\/\/www.se.senac.br\/pss\/download\/prorrogacao-do-processo-seletivo-003-2022\/?wpdmdl=159&refresh=6a04cf12add091778700050\">Download<\/a>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<\/div><div class='col-lg-12 col-md-6 col-12'><!-- WPDM Link Template: Default Template -->\n\n<div class=\"link-template-default card mb-2\">\n    <div class=\"card-body\">\n        <div class=\"media\">\n            <div class=\"mr-3 img-48\"><img decoding=\"async\" class=\"wpdm_icon\" alt=\"\u00edcone\" src=\"https:\/\/www.se.senac.br\/pss\/wp-content\/plugins\/download-manager\/assets\/file-type-icons\/pdf.svg\" \/><\/div>\n            <div class=\"media-body\">\n                <h3 class=\"package-title\"><a href='https:\/\/www.se.senac.br\/pss\/download\/sexta-convocacao-pss-003-2022\/'>Sexta Convoca\u00e7\u00e3o PSS 003\/2022<\/a><\/h3>\n                <div class=\"text-muted text-small\"><i class=\"fas fa-copy\"><\/i> 1  arquivo(s) <i class=\"fas fa-hdd ml-3\"><\/i> 136.94 KB<\/div>\n            <\/div>\n            <div class=\"ml-3\">\n                <a class='wpdm-download-link download-on-click btn btn-primary ' rel='nofollow' href='#' data-downloadurl=\"https:\/\/www.se.senac.br\/pss\/download\/sexta-convocacao-pss-003-2022\/?wpdmdl=158&refresh=6a04cf12cbefa1778700050\">Download<\/a>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<\/div><div class='col-lg-12 col-md-6 col-12'><!-- WPDM Link Template: Default Template -->\n\n<div class=\"link-template-default card mb-2\">\n    <div class=\"card-body\">\n        <div class=\"media\">\n            <div class=\"mr-3 img-48\"><img decoding=\"async\" class=\"wpdm_icon\" alt=\"\u00edcone\" src=\"https:\/\/www.se.senac.br\/pss\/wp-content\/plugins\/download-manager\/assets\/file-type-icons\/pdf.svg\" \/><\/div>\n            <div class=\"media-body\">\n                <h3 class=\"package-title\"><a href='https:\/\/www.se.senac.br\/pss\/download\/quinta-convocacao-pss-003-2022\/'>Quinta Convoca\u00e7\u00e3o PSS 003\/2022<\/a><\/h3>\n                <div class=\"text-muted text-small\"><i class=\"fas fa-copy\"><\/i> 1  arquivo(s) <i class=\"fas fa-hdd ml-3\"><\/i> 45.62 KB<\/div>\n            <\/div>\n            <div class=\"ml-3\">\n                <a class='wpdm-download-link download-on-click btn btn-primary ' rel='nofollow' href='#' data-downloadurl=\"https:\/\/www.se.senac.br\/pss\/download\/quinta-convocacao-pss-003-2022\/?wpdmdl=157&refresh=6a04cf12ea1861778700050\">Download<\/a>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<\/div><div class='col-lg-12 col-md-6 col-12'><!-- WPDM Link Template: Default Template -->\n\n<div class=\"link-template-default card mb-2\">\n    <div class=\"card-body\">\n        <div class=\"media\">\n            <div class=\"mr-3 img-48\"><img decoding=\"async\" class=\"wpdm_icon\" alt=\"\u00edcone\" src=\"https:\/\/www.se.senac.br\/pss\/wp-content\/plugins\/download-manager\/assets\/file-type-icons\/pdf.svg\" \/><\/div>\n            <div class=\"media-body\">\n                <h3 class=\"package-title\"><a href='https:\/\/www.se.senac.br\/pss\/download\/quarta-convocacao-pss-003-2022\/'>Quarta Convoca\u00e7\u00e3o PSS 003\/2022<\/a><\/h3>\n                <div class=\"text-muted text-small\"><i class=\"fas fa-copy\"><\/i> 1  arquivo(s) <i class=\"fas fa-hdd ml-3\"><\/i> 45.41 KB<\/div>\n            <\/div>\n            <div class=\"ml-3\">\n                <a class='wpdm-download-link download-on-click btn btn-primary ' rel='nofollow' href='#' data-downloadurl=\"https:\/\/www.se.senac.br\/pss\/download\/quarta-convocacao-pss-003-2022\/?wpdmdl=156&refresh=6a04cf131ce9e1778700051\">Download<\/a>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<\/div><div class='col-lg-12 col-md-6 col-12'><!-- WPDM Link Template: Default Template -->\n\n<div class=\"link-template-default card mb-2\">\n    <div class=\"card-body\">\n        <div class=\"media\">\n            <div class=\"mr-3 img-48\"><img decoding=\"async\" class=\"wpdm_icon\" alt=\"\u00edcone\" src=\"https:\/\/www.se.senac.br\/pss\/wp-content\/plugins\/download-manager\/assets\/file-type-icons\/pdf.svg\" \/><\/div>\n            <div class=\"media-body\">\n                <h3 class=\"package-title\"><a href='https:\/\/www.se.senac.br\/pss\/download\/terceira-convocacao-pss-003-2022\/'>Terceira Convoca\u00e7\u00e3o PSS 003\/2022<\/a><\/h3>\n                <div class=\"text-muted text-small\"><i class=\"fas fa-copy\"><\/i> 1  arquivo(s) <i class=\"fas fa-hdd ml-3\"><\/i> 45.29 KB<\/div>\n            <\/div>\n            <div class=\"ml-3\">\n                <a class='wpdm-download-link download-on-click btn btn-primary ' rel='nofollow' href='#' data-downloadurl=\"https:\/\/www.se.senac.br\/pss\/download\/terceira-convocacao-pss-003-2022\/?wpdmdl=155&refresh=6a04cf133b0fe1778700051\">Download<\/a>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<\/div><div class='col-lg-12 col-md-6 col-12'><!-- WPDM Link Template: Default Template -->\n\n<div class=\"link-template-default card mb-2\">\n    <div class=\"card-body\">\n        <div class=\"media\">\n            <div class=\"mr-3 img-48\"><img decoding=\"async\" class=\"wpdm_icon\" alt=\"\u00edcone\" src=\"https:\/\/www.se.senac.br\/pss\/wp-content\/plugins\/download-manager\/assets\/file-type-icons\/pdf.svg\" \/><\/div>\n            <div class=\"media-body\">\n                <h3 class=\"package-title\"><a href='https:\/\/www.se.senac.br\/pss\/download\/segunda-convocacao-pss-003-2022\/'>Segunda Convoca\u00e7\u00e3o PSS 003\/2022<\/a><\/h3>\n                <div class=\"text-muted text-small\"><i class=\"fas fa-copy\"><\/i> 1  arquivo(s) <i class=\"fas fa-hdd ml-3\"><\/i> 46.86 KB<\/div>\n            <\/div>\n            <div class=\"ml-3\">\n                <a class='wpdm-download-link download-on-click btn btn-primary ' rel='nofollow' href='#' data-downloadurl=\"https:\/\/www.se.senac.br\/pss\/download\/segunda-convocacao-pss-003-2022\/?wpdmdl=154&refresh=6a04cf135e9851778700051\">Download<\/a>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<\/div><div class='col-lg-12 col-md-6 col-12'><!-- WPDM Link Template: Default Template -->\n\n<div class=\"link-template-default card mb-2\">\n    <div class=\"card-body\">\n        <div class=\"media\">\n            <div class=\"mr-3 img-48\"><img decoding=\"async\" class=\"wpdm_icon\" alt=\"\u00edcone\" src=\"https:\/\/www.se.senac.br\/pss\/wp-content\/plugins\/download-manager\/assets\/file-type-icons\/pdf.svg\" \/><\/div>\n            <div class=\"media-body\">\n                <h3 class=\"package-title\"><a href='https:\/\/www.se.senac.br\/pss\/download\/primeira-convocacao-pss-003-2022\/'>Primeira Convoca\u00e7\u00e3o PSS 003\/2022<\/a><\/h3>\n                <div class=\"text-muted text-small\"><i class=\"fas fa-copy\"><\/i> 1  arquivo(s) <i class=\"fas fa-hdd ml-3\"><\/i> 45.82 KB<\/div>\n            <\/div>\n            <div class=\"ml-3\">\n                <a class='wpdm-download-link download-on-click btn btn-primary ' rel='nofollow' href='#' data-downloadurl=\"https:\/\/www.se.senac.br\/pss\/download\/primeira-convocacao-pss-003-2022\/?wpdmdl=153&refresh=6a04cf137ccc91778700051\">Download<\/a>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<\/div><div class='col-lg-12 col-md-6 col-12'><!-- WPDM Link Template: Default Template -->\n\n<div class=\"link-template-default card mb-2\">\n    <div class=\"card-body\">\n        <div class=\"media\">\n            <div class=\"mr-3 img-48\"><img decoding=\"async\" class=\"wpdm_icon\" alt=\"\u00edcone\" src=\"https:\/\/www.se.senac.br\/pss\/wp-content\/plugins\/download-manager\/assets\/file-type-icons\/pdf.svg\" \/><\/div>\n            <div class=\"media-body\">\n                <h3 class=\"package-title\"><a href='https:\/\/www.se.senac.br\/pss\/download\/homologacao-pss-003-2022\/'>Homologa\u00e7\u00e3o PSS 003\/2022<\/a><\/h3>\n                <div class=\"text-muted text-small\"><i class=\"fas fa-copy\"><\/i> 1  arquivo(s) <i class=\"fas fa-hdd ml-3\"><\/i> 61.21 KB<\/div>\n            <\/div>\n            <div class=\"ml-3\">\n                <a class='wpdm-download-link download-on-click btn btn-primary ' rel='nofollow' href='#' data-downloadurl=\"https:\/\/www.se.senac.br\/pss\/download\/homologacao-pss-003-2022\/?wpdmdl=152&refresh=6a04cf139b1731778700051\">Download<\/a>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<\/div><div class='col-lg-12 col-md-6 col-12'><!-- WPDM Link Template: Default Template -->\n\n<div class=\"link-template-default card mb-2\">\n    <div class=\"card-body\">\n        <div class=\"media\">\n            <div class=\"mr-3 img-48\"><img decoding=\"async\" class=\"wpdm_icon\" alt=\"\u00edcone\" src=\"https:\/\/www.se.senac.br\/pss\/wp-content\/plugins\/download-manager\/assets\/file-type-icons\/pdf.svg\" \/><\/div>\n            <div class=\"media-body\">\n                <h3 class=\"package-title\"><a href='https:\/\/www.se.senac.br\/pss\/download\/resultado-final-pss-003-2022\/'>Resultado Final PSS 003\/2022<\/a><\/h3>\n                <div class=\"text-muted text-small\"><i class=\"fas fa-copy\"><\/i> 1  arquivo(s) <i class=\"fas fa-hdd ml-3\"><\/i> 50.43 KB<\/div>\n            <\/div>\n            <div class=\"ml-3\">\n                <a class='wpdm-download-link download-on-click btn btn-primary ' rel='nofollow' href='#' data-downloadurl=\"https:\/\/www.se.senac.br\/pss\/download\/resultado-final-pss-003-2022\/?wpdmdl=151&refresh=6a04cf13bbaa31778700051\">Download<\/a>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<\/div><div class='col-lg-12 col-md-6 col-12'><!-- WPDM Link Template: Default Template -->\n\n<div class=\"link-template-default card mb-2\">\n    <div class=\"card-body\">\n        <div class=\"media\">\n            <div class=\"mr-3 img-48\"><img decoding=\"async\" class=\"wpdm_icon\" alt=\"\u00edcone\" src=\"https:\/\/www.se.senac.br\/pss\/wp-content\/plugins\/download-manager\/assets\/file-type-icons\/pdf.svg\" \/><\/div>\n            <div class=\"media-body\">\n                <h3 class=\"package-title\"><a href='https:\/\/www.se.senac.br\/pss\/download\/resultado-da-3a-etapa-avaliacao-de-habilidades-comportamentais-pss-003-2022\/'>Resultado da 3a Etapa - Avalia\u00e7\u00e3o de Habilidades Comportamentais PSS 003\/2022<\/a><\/h3>\n                <div class=\"text-muted text-small\"><i class=\"fas fa-copy\"><\/i> 1  arquivo(s) <i class=\"fas fa-hdd ml-3\"><\/i> 53.41 KB<\/div>\n            <\/div>\n            <div class=\"ml-3\">\n                <a class='wpdm-download-link download-on-click btn btn-primary ' rel='nofollow' href='#' data-downloadurl=\"https:\/\/www.se.senac.br\/pss\/download\/resultado-da-3a-etapa-avaliacao-de-habilidades-comportamentais-pss-003-2022\/?wpdmdl=150&refresh=6a04cf13d877d1778700051\">Download<\/a>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<\/div><div class='col-lg-12 col-md-6 col-12'><!-- WPDM Link Template: Default Template -->\n\n<div class=\"link-template-default card mb-2\">\n    <div class=\"card-body\">\n        <div class=\"media\">\n            <div class=\"mr-3 img-48\"><img decoding=\"async\" class=\"wpdm_icon\" alt=\"\u00edcone\" src=\"https:\/\/www.se.senac.br\/pss\/wp-content\/plugins\/download-manager\/assets\/file-type-icons\/pdf.svg\" \/><\/div>\n            <div class=\"media-body\">\n                <h3 class=\"package-title\"><a href='https:\/\/www.se.senac.br\/pss\/download\/convocacao-dos-candidatos-para-3a-etapa-avaliacao-de-habilidades-comportamentais-dinamica-de-grupo-pss-003-2022\/'>Convoca\u00e7\u00e3o dos Candidatos para 3\u00aa etapa \u2013 Avalia\u00e7\u00e3o de Habilidades Comportamentais \u2013 Din\u00e2mica de Grupo PSS 003\/2022<\/a><\/h3>\n                <div class=\"text-muted text-small\"><i class=\"fas fa-copy\"><\/i> 1  arquivo(s) <i class=\"fas fa-hdd ml-3\"><\/i> 64.25 KB<\/div>\n            <\/div>\n            <div class=\"ml-3\">\n                <a class='wpdm-download-link download-on-click btn btn-primary ' rel='nofollow' href='#' data-downloadurl=\"https:\/\/www.se.senac.br\/pss\/download\/convocacao-dos-candidatos-para-3a-etapa-avaliacao-de-habilidades-comportamentais-dinamica-de-grupo-pss-003-2022\/?wpdmdl=149&refresh=6a04cf1401f171778700052\">Download<\/a>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<\/div><div class='col-lg-12 col-md-6 col-12'><!-- WPDM Link Template: Default Template -->\n\n<div class=\"link-template-default card mb-2\">\n    <div class=\"card-body\">\n        <div class=\"media\">\n            <div class=\"mr-3 img-48\"><img decoding=\"async\" class=\"wpdm_icon\" alt=\"\u00edcone\" src=\"https:\/\/www.se.senac.br\/pss\/wp-content\/plugins\/download-manager\/assets\/file-type-icons\/pdf.svg\" \/><\/div>\n            <div class=\"media-body\">\n                <h3 class=\"package-title\"><a href='https:\/\/www.se.senac.br\/pss\/download\/resultado-da-2-etapa-avaliacao-de-conhecimento-pss-003-2022\/'>Resultado da 2 Etapa Avalia\u00e7\u00e3o de Conhecimento PSS 003\/2022<\/a><\/h3>\n                <div class=\"text-muted text-small\"><i class=\"fas fa-copy\"><\/i> 1  arquivo(s) <i class=\"fas fa-hdd ml-3\"><\/i> 54.01 KB<\/div>\n            <\/div>\n            <div class=\"ml-3\">\n                <a class='wpdm-download-link download-on-click btn btn-primary ' rel='nofollow' href='#' data-downloadurl=\"https:\/\/www.se.senac.br\/pss\/download\/resultado-da-2-etapa-avaliacao-de-conhecimento-pss-003-2022\/?wpdmdl=148&refresh=6a04cf14219601778700052\">Download<\/a>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<\/div><div class='col-lg-12 col-md-6 col-12'><!-- WPDM Link Template: Default Template -->\n\n<div class=\"link-template-default card mb-2\">\n    <div class=\"card-body\">\n        <div class=\"media\">\n            <div class=\"mr-3 img-48\"><img decoding=\"async\" class=\"wpdm_icon\" alt=\"\u00edcone\" src=\"https:\/\/www.se.senac.br\/pss\/wp-content\/plugins\/download-manager\/assets\/file-type-icons\/pdf.svg\" \/><\/div>\n            <div class=\"media-body\">\n                <h3 class=\"package-title\"><a href='https:\/\/www.se.senac.br\/pss\/download\/convocacao-para-2-etapa-pss-003-2022\/'>Convoca\u00e7\u00e3o para 2 Etapa PSS 003\/2022<\/a><\/h3>\n                <div class=\"text-muted text-small\"><i class=\"fas fa-copy\"><\/i> 1  arquivo(s) <i class=\"fas fa-hdd ml-3\"><\/i> 381.89 KB<\/div>\n            <\/div>\n            <div class=\"ml-3\">\n                <a class='wpdm-download-link download-on-click btn btn-primary ' rel='nofollow' href='#' data-downloadurl=\"https:\/\/www.se.senac.br\/pss\/download\/convocacao-para-2-etapa-pss-003-2022\/?wpdmdl=147&refresh=6a04cf14479a51778700052\">Download<\/a>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<\/div><div class='col-lg-12 col-md-6 col-12'><!-- WPDM Link Template: Default Template -->\n\n<div class=\"link-template-default card mb-2\">\n    <div class=\"card-body\">\n        <div class=\"media\">\n            <div class=\"mr-3 img-48\"><img decoding=\"async\" class=\"wpdm_icon\" alt=\"\u00edcone\" src=\"https:\/\/www.se.senac.br\/pss\/wp-content\/plugins\/download-manager\/assets\/file-type-icons\/pdf.svg\" \/><\/div>\n            <div class=\"media-body\">\n                <h3 class=\"package-title\"><a href='https:\/\/www.se.senac.br\/pss\/download\/resultados-da-analise-curricular-e-documental\/'>Resultados da An\u00e1lise Curricular e Documental 003\/2022<\/a><\/h3>\n                <div class=\"text-muted text-small\"><i class=\"fas fa-copy\"><\/i> 1  arquivo(s) <i class=\"fas fa-hdd ml-3\"><\/i> 37.18 KB<\/div>\n            <\/div>\n            <div class=\"ml-3\">\n                <a class='wpdm-download-link download-on-click btn btn-primary ' rel='nofollow' href='#' data-downloadurl=\"https:\/\/www.se.senac.br\/pss\/download\/resultados-da-analise-curricular-e-documental\/?wpdmdl=146&refresh=6a04cf14682841778700052\">Download<\/a>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<\/div><div class='col-lg-12 col-md-6 col-12'><!-- WPDM Link Template: Default Template -->\n\n<div class=\"link-template-default card mb-2\">\n    <div class=\"card-body\">\n        <div class=\"media\">\n            <div class=\"mr-3 img-48\"><img decoding=\"async\" class=\"wpdm_icon\" alt=\"\u00edcone\" src=\"https:\/\/www.se.senac.br\/pss\/wp-content\/plugins\/download-manager\/assets\/file-type-icons\/pdf.svg\" \/><\/div>\n            <div class=\"media-body\">\n                <h3 class=\"package-title\"><a href='https:\/\/www.se.senac.br\/pss\/download\/lista-de-inscritos-003-2022\/'>Lista de Inscritos 003\/2022<\/a><\/h3>\n                <div class=\"text-muted text-small\"><i class=\"fas fa-copy\"><\/i> 1  arquivo(s) <i class=\"fas fa-hdd ml-3\"><\/i> 38.05 KB<\/div>\n            <\/div>\n            <div class=\"ml-3\">\n                <a class='wpdm-download-link download-on-click btn btn-primary ' rel='nofollow' href='#' data-downloadurl=\"https:\/\/www.se.senac.br\/pss\/download\/lista-de-inscritos-003-2022\/?wpdmdl=145&refresh=6a04cf14855f41778700052\">Download<\/a>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<\/div><div class='col-lg-12 col-md-6 col-12'><!-- WPDM Link Template: Default Template -->\n\n<div class=\"link-template-default card mb-2\">\n    <div class=\"card-body\">\n        <div class=\"media\">\n            <div class=\"mr-3 img-48\"><img decoding=\"async\" class=\"wpdm_icon\" alt=\"\u00edcone\" src=\"https:\/\/www.se.senac.br\/pss\/wp-content\/plugins\/download-manager\/assets\/file-type-icons\/pdf.svg\" \/><\/div>\n            <div class=\"media-body\">\n                <h3 class=\"package-title\"><a href='https:\/\/www.se.senac.br\/pss\/download\/comunicado-de-abertura-de-processo-seletivo-003-2022\/'>Comunicado de Abertura de Processo Seletivo 003\/2022<\/a><\/h3>\n                <div class=\"text-muted text-small\"><i class=\"fas fa-copy\"><\/i> 1  arquivo(s) <i class=\"fas fa-hdd ml-3\"><\/i> 163.88 KB<\/div>\n            <\/div>\n            <div class=\"ml-3\">\n                <a class='wpdm-download-link download-on-click btn btn-primary ' rel='nofollow' href='#' data-downloadurl=\"https:\/\/www.se.senac.br\/pss\/download\/comunicado-de-abertura-de-processo-seletivo-003-2022\/?wpdmdl=141&refresh=6a04cf14a395d1778700052\">Download<\/a>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<\/div><\/div>            <div style='clear:both'><\/div><div class='text-center'><ul class='pagination wpdm-pagination pagination-centered text-center async'><\/ul><\/div><div style='clear:both'><\/div>        <\/div>\n\n        <div style='clear:both'><\/div>\n    <\/div>\n<\/div>\n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A inscri\u00e7\u00e3o ser\u00e1 feita em uma plataforma externa (e-inscri\u00e7\u00e3o).\u00a0 Ao clicar no bot\u00e3o abaixo,\u00a0 n\u00e3o \u00e9 obrigat\u00f3ria a cria\u00e7\u00e3o de uma conta, basta efetuar o cadastro e aguardar o email de confirma\u00e7\u00e3o. Lembre-se, n\u00e3o h\u00e1 taxas ou valores a serem pagos. INSCRI\u00c7\u00d5ES ENCERRADAS<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-142","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PSS 03\/2022 - Processo Seletivo Senac-SE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.se.senac.br\/pss\/pss-03-2022\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PSS 03\/2022 - Processo Seletivo Senac-SE\" \/>\n<meta property=\"og:description\" content=\"A inscri\u00e7\u00e3o ser\u00e1 feita em uma plataforma externa (e-inscri\u00e7\u00e3o).\u00a0 Ao clicar no bot\u00e3o abaixo,\u00a0 n\u00e3o \u00e9 obrigat\u00f3ria a cria\u00e7\u00e3o de uma conta, basta efetuar o cadastro e aguardar o email de confirma\u00e7\u00e3o. Lembre-se, n\u00e3o h\u00e1 taxas ou valores a serem pagos. INSCRI\u00c7\u00d5ES ENCERRADAS\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.se.senac.br\/pss\/pss-03-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"Processo Seletivo Senac-SE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.se.senac.br\\\/pss\\\/pss-03-2022\\\/\",\"url\":\"https:\\\/\\\/www.se.senac.br\\\/pss\\\/pss-03-2022\\\/\",\"name\":\"PSS 03\\\/2022 - Processo Seletivo Senac-SE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.se.senac.br\\\/pss\\\/#website\"},\"datePublished\":\"2024-03-18T20:32:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.se.senac.br\\\/pss\\\/pss-03-2022\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.se.senac.br\\\/pss\\\/pss-03-2022\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.se.senac.br\\\/pss\\\/pss-03-2022\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.se.senac.br\\\/pss\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PSS 03\\\/2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.se.senac.br\\\/pss\\\/#website\",\"url\":\"https:\\\/\\\/www.se.senac.br\\\/pss\\\/\",\"name\":\"Processo Seletivo Senac-SE\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.se.senac.br\\\/pss\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.se.senac.br\\\/pss\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.se.senac.br\\\/pss\\\/#organization\",\"name\":\"Processo Seletivo Senac-SE\",\"url\":\"https:\\\/\\\/www.se.senac.br\\\/pss\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.se.senac.br\\\/pss\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.se.senac.br\\\/pss\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/marca-Senac-fecomercio-Sesc-horizontal-e1667480854221.png\",\"contentUrl\":\"https:\\\/\\\/www.se.senac.br\\\/pss\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/marca-Senac-fecomercio-Sesc-horizontal-e1667480854221.png\",\"width\":300,\"height\":97,\"caption\":\"Processo Seletivo Senac-SE\"},\"image\":{\"@id\":\"https:\\\/\\\/www.se.senac.br\\\/pss\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PSS 03\/2022 - Processo Seletivo Senac-SE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.se.senac.br\/pss\/pss-03-2022\/","og_locale":"pt_BR","og_type":"article","og_title":"PSS 03\/2022 - Processo Seletivo Senac-SE","og_description":"A inscri\u00e7\u00e3o ser\u00e1 feita em uma plataforma externa (e-inscri\u00e7\u00e3o).\u00a0 Ao clicar no bot\u00e3o abaixo,\u00a0 n\u00e3o \u00e9 obrigat\u00f3ria a cria\u00e7\u00e3o de uma conta, basta efetuar o cadastro e aguardar o email de confirma\u00e7\u00e3o. Lembre-se, n\u00e3o h\u00e1 taxas ou valores a serem pagos. INSCRI\u00c7\u00d5ES ENCERRADAS","og_url":"https:\/\/www.se.senac.br\/pss\/pss-03-2022\/","og_site_name":"Processo Seletivo Senac-SE","twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.se.senac.br\/pss\/pss-03-2022\/","url":"https:\/\/www.se.senac.br\/pss\/pss-03-2022\/","name":"PSS 03\/2022 - Processo Seletivo Senac-SE","isPartOf":{"@id":"https:\/\/www.se.senac.br\/pss\/#website"},"datePublished":"2024-03-18T20:32:48+00:00","breadcrumb":{"@id":"https:\/\/www.se.senac.br\/pss\/pss-03-2022\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.se.senac.br\/pss\/pss-03-2022\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.se.senac.br\/pss\/pss-03-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.se.senac.br\/pss\/"},{"@type":"ListItem","position":2,"name":"PSS 03\/2022"}]},{"@type":"WebSite","@id":"https:\/\/www.se.senac.br\/pss\/#website","url":"https:\/\/www.se.senac.br\/pss\/","name":"Processo Seletivo Senac-SE","description":"","publisher":{"@id":"https:\/\/www.se.senac.br\/pss\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.se.senac.br\/pss\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.se.senac.br\/pss\/#organization","name":"Processo Seletivo Senac-SE","url":"https:\/\/www.se.senac.br\/pss\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.se.senac.br\/pss\/#\/schema\/logo\/image\/","url":"https:\/\/www.se.senac.br\/pss\/wp-content\/uploads\/2023\/02\/marca-Senac-fecomercio-Sesc-horizontal-e1667480854221.png","contentUrl":"https:\/\/www.se.senac.br\/pss\/wp-content\/uploads\/2023\/02\/marca-Senac-fecomercio-Sesc-horizontal-e1667480854221.png","width":300,"height":97,"caption":"Processo Seletivo Senac-SE"},"image":{"@id":"https:\/\/www.se.senac.br\/pss\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.se.senac.br\/pss\/wp-json\/wp\/v2\/pages\/142","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.se.senac.br\/pss\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.se.senac.br\/pss\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.se.senac.br\/pss\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.se.senac.br\/pss\/wp-json\/wp\/v2\/comments?post=142"}],"version-history":[{"count":1,"href":"https:\/\/www.se.senac.br\/pss\/wp-json\/wp\/v2\/pages\/142\/revisions"}],"predecessor-version":[{"id":143,"href":"https:\/\/www.se.senac.br\/pss\/wp-json\/wp\/v2\/pages\/142\/revisions\/143"}],"wp:attachment":[{"href":"https:\/\/www.se.senac.br\/pss\/wp-json\/wp\/v2\/media?parent=142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}